{"id":6179,"count":1,"description":"","link":"https:\/\/agricultural-gearboxes.com\/th\/tag\/right-angle-pto-gearbox-dar-es-salaam-united-republic-of-tanzania\/","name":"right angle pto gearbox Dar es Salaam United Republic of Tanzania","slug":"right-angle-pto-gearbox-dar-es-salaam-united-republic-of-tanzania","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/agricultural-gearboxes.com\/th\/wp-json\/wp\/v2\/tags\/6179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agricultural-gearboxes.com\/th\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/agricultural-gearboxes.com\/th\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/agricultural-gearboxes.com\/th\/wp-json\/wp\/v2\/posts?tags=6179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}