{"id":3589,"count":3,"description":"","link":"https:\/\/agricultural-gearboxes.com\/ru\/tag\/belt-drive-replacement\/","name":"belt drive replacement","slug":"belt-drive-replacement","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/agricultural-gearboxes.com\/ru\/wp-json\/wp\/v2\/tags\/3589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agricultural-gearboxes.com\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/agricultural-gearboxes.com\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/agricultural-gearboxes.com\/ru\/wp-json\/wp\/v2\/posts?tags=3589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}