{"id":1974,"count":1,"description":"","link":"https:\/\/agricultural-gearboxes.com\/id\/tag\/worm-and-wheel-drive\/","name":"worm and wheel drive","slug":"worm-and-wheel-drive","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/agricultural-gearboxes.com\/id\/wp-json\/wp\/v2\/tags\/1974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agricultural-gearboxes.com\/id\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/agricultural-gearboxes.com\/id\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/agricultural-gearboxes.com\/id\/wp-json\/wp\/v2\/posts?tags=1974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}