{"id":3133,"count":19,"description":"","link":"https:\/\/agricultural-gearboxes.com\/hi\/tag\/steel-sprocket\/","name":"steel sprocket","slug":"steel-sprocket","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/agricultural-gearboxes.com\/hi\/wp-json\/wp\/v2\/tags\/3133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agricultural-gearboxes.com\/hi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/agricultural-gearboxes.com\/hi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/agricultural-gearboxes.com\/hi\/wp-json\/wp\/v2\/posts?tags=3133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}